{"id":240193,"date":"2024-06-12T17:09:38","date_gmt":"2024-06-12T15:09:38","guid":{"rendered":"https:\/\/trade-mueller-dev.startupblitz.de\/shop\/unkategorisiert\/herren-hemd\/"},"modified":"2024-10-28T18:30:22","modified_gmt":"2024-10-28T17:30:22","slug":"herren-hemd-8","status":"publish","type":"product","link":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/","title":{"rendered":"Herren-Hemd"},"content":{"rendered":"<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/\">plus<span class=\"screen-reader-text\"> from Herren-Hemd<\/span><\/a><\/p>\n","protected":false},"featured_media":58496,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"pwb-brand":[4567],"product_brand":[],"product_cat":[3357,1262,3354,3416,3430,3427],"product_tag":[],"class_list":{"0":"post-240193","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"pwb-brand-id-identity-fr","7":"product_cat-manches-longues","8":"product_cat-tout","9":"product_cat-blouses-chemises","10":"product_cat-corporate-wear-fr","11":"product_cat-manches-longues-cw-fr","12":"product_cat-blouses-chemises-cw-fr","13":"pa_color-blanc","14":"pa_color-bleu-clair","15":"pa_color-noir-3","16":"pa_color-group-blanc","17":"pa_color-group-bleu","18":"pa_color-group-noir","19":"pa_fit-regular-fit","20":"pa_gender-hommes","21":"pa_shirtsizes-37-38","22":"pa_shirtsizes-39-40","23":"pa_shirtsizes-41-42","24":"pa_shirtsizes-43-44","25":"pa_shirtsizes-45-46","26":"pa_shirtsizes-47-48","28":"","29":"instock","30":"taxable","31":"shipping-taxable","32":"purchasable","33":"product-type-variable"},"acf":[],"yoast_head":"<title>Herren-Hemd - M\u00dcLLER TRADE<\/title>\n<meta name=\"description\" content=\"Herren-Hemd - M\u00dcLLER TRADE\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Herren-Hemd - M\u00dcLLER TRADE\" \/>\n<meta property=\"og:description\" content=\"Herren-Hemd - M\u00dcLLER TRADE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00dcLLER TRADE\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-28T17:30:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trade-mueller-dev.startupblitz.de\/wp-content\/uploads\/sites\/2\/id_0256_001_profil_p-jpg-avif.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/\",\"url\":\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/\",\"name\":\"Herren-Hemd - M\u00dcLLER TRADE\",\"isPartOf\":{\"@id\":\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/trade-mueller-dev.startupblitz.de\/wp-content\/uploads\/sites\/2\/id_0256_001_profil_p-jpg-avif.webp\",\"datePublished\":\"2024-06-12T15:09:38+00:00\",\"dateModified\":\"2024-10-28T17:30:22+00:00\",\"description\":\"Herren-Hemd - M\u00dcLLER TRADE\",\"breadcrumb\":{\"@id\":\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/#primaryimage\",\"url\":\"https:\/\/trade-mueller-dev.startupblitz.de\/wp-content\/uploads\/sites\/2\/id_0256_001_profil_p-jpg-avif.webp\",\"contentUrl\":\"https:\/\/trade-mueller-dev.startupblitz.de\/wp-content\/uploads\/sites\/2\/id_0256_001_profil_p-jpg-avif.webp\",\"width\":800,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Herren-Hemd\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/#website\",\"url\":\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/\",\"name\":\"M\u00fcller Trade\",\"description\":\"IHR B2B SHOP F\u00dcR BERUFSBEKLEIDUNG\",\"publisher\":{\"@id\":\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/#organization\",\"name\":\"M\u00fcller Trade Corporate Clothing\",\"url\":\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/trade-mueller-dev.startupblitz.de\/wp-content\/uploads\/sites\/2\/cropped-cropped-mt-icon.png\",\"contentUrl\":\"https:\/\/trade-mueller-dev.startupblitz.de\/wp-content\/uploads\/sites\/2\/cropped-cropped-mt-icon.png\",\"width\":512,\"height\":512,\"caption\":\"M\u00fcller Trade Corporate Clothing\"},\"image\":{\"@id\":\"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>","yoast_head_json":{"title":"Herren-Hemd - M\u00dcLLER TRADE","description":"Herren-Hemd - M\u00dcLLER TRADE","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Herren-Hemd - M\u00dcLLER TRADE","og_description":"Herren-Hemd - M\u00dcLLER TRADE","og_url":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/","og_site_name":"M\u00dcLLER TRADE","article_modified_time":"2024-10-28T17:30:22+00:00","og_image":[{"width":800,"height":1200,"url":"https:\/\/trade-mueller-dev.startupblitz.de\/wp-content\/uploads\/sites\/2\/id_0256_001_profil_p-jpg-avif.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/","url":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/","name":"Herren-Hemd - M\u00dcLLER TRADE","isPartOf":{"@id":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/#primaryimage"},"image":{"@id":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/#primaryimage"},"thumbnailUrl":"https:\/\/trade-mueller-dev.startupblitz.de\/wp-content\/uploads\/sites\/2\/id_0256_001_profil_p-jpg-avif.webp","datePublished":"2024-06-12T15:09:38+00:00","dateModified":"2024-10-28T17:30:22+00:00","description":"Herren-Hemd - M\u00dcLLER TRADE","breadcrumb":{"@id":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/#primaryimage","url":"https:\/\/trade-mueller-dev.startupblitz.de\/wp-content\/uploads\/sites\/2\/id_0256_001_profil_p-jpg-avif.webp","contentUrl":"https:\/\/trade-mueller-dev.startupblitz.de\/wp-content\/uploads\/sites\/2\/id_0256_001_profil_p-jpg-avif.webp","width":800,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/corporate-wear-fr\/blouses-chemises-cw-fr\/manches-longues-cw-fr\/herren-hemd-8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Herren-Hemd"}]},{"@type":"WebSite","@id":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/#website","url":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/","name":"M\u00fcller Trade","description":"IHR B2B SHOP F\u00dcR BERUFSBEKLEIDUNG","publisher":{"@id":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/#organization","name":"M\u00fcller Trade Corporate Clothing","url":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/trade-mueller-dev.startupblitz.de\/wp-content\/uploads\/sites\/2\/cropped-cropped-mt-icon.png","contentUrl":"https:\/\/trade-mueller-dev.startupblitz.de\/wp-content\/uploads\/sites\/2\/cropped-cropped-mt-icon.png","width":512,"height":512,"caption":"M\u00fcller Trade Corporate Clothing"},"image":{"@id":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/#\/schema\/logo\/image\/"}}]}},"brands":[{"id":4567,"name":"ID Identity","slug":"id-identity-fr"}],"_links":{"self":[{"href":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/wp-json\/wp\/v2\/product\/240193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/wp-json\/wp\/v2\/media\/58496"}],"wp:attachment":[{"href":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/wp-json\/wp\/v2\/media?parent=240193"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/wp-json\/wp\/v2\/pwb-brand?post=240193"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/wp-json\/wp\/v2\/product_brand?post=240193"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/wp-json\/wp\/v2\/product_cat?post=240193"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/trade-mueller-dev.startupblitz.de\/fr\/wp-json\/wp\/v2\/product_tag?post=240193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}